{"id":14934,"date":"2026-04-26T08:47:41","date_gmt":"2026-04-26T08:47:41","guid":{"rendered":"https:\/\/gastora.eu\/?post_type=product&#038;p=14934"},"modified":"2026-04-28T16:57:28","modified_gmt":"2026-04-28T16:57:28","slug":"ptrin-spirale-ptrin-pte-8-l-45-kg-de-pte-rose","status":"publish","type":"product","link":"https:\/\/gastora.eu\/en\/product\/ptrin-spirale-ptrin-pte-8-l-45-kg-de-pte-rose\/","title":{"rendered":"P\u00e9trin \u00e0 spirale \/ p\u00e9trin \u00e0 p\u00e2te &#8211; 8 L &#8211; 4,5 kg de p\u00e2te &#8211; rose"},"content":{"rendered":"<p>P\u00e9trir de grandes quantit\u00e9s de p\u00e2te \u00e0 la main peut \u00eatre une t\u00e2che ardue. Avec l&#8217;aide de ce p\u00e9trin de 8 litres, vous pouvez facilement transformer 4,5 kg d&#8217;ingr\u00e9dients en une p\u00e2te lisse. La quantit\u00e9 maximale de farine est de 3 kg et la quantit\u00e9 maximale de p\u00e2te est de 4,5 kg. Vous pouvez \u00e9galement p\u00e9trir de plus petites quantit\u00e9s de p\u00e2te, \u00e0 condition qu&#8217;elles ne soient pas inf\u00e9rieures \u00e0 1,5 kg. Le crochet p\u00e9trisseur et le bol de m\u00e9lange tournent tous les deux pour s&#8217;assurer que tous les ingr\u00e9dients sont bien m\u00e9lang\u00e9s et pr\u00eats pour la cuisson. Ce batteur est un atout pour toute cuisine professionnelle dans les restaurants, les boulangeries et les caf\u00e9s. Il est \u00e9galement disponible dans une gamme de couleurs. Gr\u00e2ce \u00e0 la minuterie pratique, vous pouvez laisser le mixeur travailler seul.<\/p>\n<h3>Travailler en toute s\u00e9curit\u00e9<\/h3>\n<p>Gr\u00e2ce \u00e0 l&#8217;interrupteur de s\u00e9curit\u00e9, vous pouvez \u00e9galement \u00eatre s\u00fbr que votre s\u00e9curit\u00e9 est assur\u00e9e lorsque vous utilisez ce p\u00e9trin et que le moteur ne surchauffera pas. Le p\u00e9trin est \u00e9quip\u00e9 d&#8217;une cage de s\u00e9curit\u00e9 qui ferme le bol de mixage. Si la cage n&#8217;est pas compl\u00e8tement ferm\u00e9e, l&#8217;appareil ne d\u00e9marre pas. Il en va de m\u00eame si le bol de m\u00e9lange est surcharg\u00e9 d&#8217;ingr\u00e9dients. Le mixeur s&#8217;arr\u00eate automatiquement.<\/p>\n<h3>Facile \u00e0 nettoyer<\/h3>\n<p>Ce p\u00e9trin professionnel est fabriqu\u00e9 en m\u00e9tal avec un rev\u00eatement durable. Le bol et le crochet sont en acier inoxydable, ce qui est non seulement esth\u00e9tique, mais aussi tr\u00e8s facile \u00e0 nettoyer. Un chiffon humide et un d\u00e9tergent doux suffisent. Le bol de mixage n&#8217;est pas amovible, mais il est suffisamment grand pour \u00eatre facile \u00e0 nettoyer. Apr\u00e8s le nettoyage, s\u00e9chez le tout avec un chiffon doux.<\/p>\n<p><strong>Caract\u00e9ristiques<\/strong><\/p>\n<ul>\n<li>Entra\u00eenement par cha\u00eene et courroies trap\u00e9zo\u00efdales<\/li>\n<li>Poss\u00e8de \u00e9galement un mode manuel<\/li>\n<li>Comprend une minuterie jusqu&#8217;\u00e0 60 minutes<\/li>\n<li>Axe et spirale en acier inoxydable<\/li>\n<li>Protection m\u00e9tallique et interrupteur de s\u00e9curit\u00e9<\/li>\n<\/ul>\n<p><strong>Caract\u00e9ristiques du produit<\/strong><\/p>\n<ul>\n<li>Poids net : 36kg<\/li>\n<li>Capacit\u00e9 nette du bol : 7,85l<\/li>\n<li>Dimensions : 30,2 x 49,5 x 38,5 cm L30,2 x P49,5 x H38,5cm<\/li>\n<li>Dimensions du bol : \u220526 x H15cm<\/li>\n<li>Vitesse de la spirale : 159RPM<\/li>\n<li>Vitesse du bol de m\u00e9lange : 21RPM<\/li>\n<li>230V \/ 50Hz \/ 1Phase 450W<\/li>\n<li>Couleur : Rose<\/li>\n<\/ul>\n<p><strong>Production<\/strong><\/p>\n<ul>\n<li>Max : 3kg de farine<\/li>\n<li>Max : 4,5kg de p\u00e2te<\/li>\n<li>Min : 1,5kg de p\u00e2te<\/li>\n<\/ul>\n<p><strong>Note : Le bol de m\u00e9lange est fixe et ne peut pas \u00eatre enlev\u00e9.<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>Ce p\u00e9trin professionnel rose avec bol de 8 litres permet de p\u00e9trir jusqu&#8217;\u00e0 4,5 kg de p\u00e2te. Il est dot\u00e9 d&#8217;un panneau de commande facile \u00e0 utiliser, d&#8217;une minuterie et de plusieurs dispositifs de s\u00e9curit\u00e9 tels que des interrupteurs de s\u00e9curit\u00e9 et une grille de protection. Le p\u00e9trin est livr\u00e9 avec un crochet en acier inoxydable et un bol de m\u00e9lange fixe.<\/p>","protected":false},"featured_media":8601,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[481],"product_tag":[],"class_list":{"0":"post-14934","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-petrins-2","8":"first","9":"instock","10":"sale","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>P\u00e9trin \u00e0 spirale \/ p\u00e9trin \u00e0 p\u00e2te - 8 L - 4,5 kg de p\u00e2te - rose - Gastora<\/title>\n<meta name=\"description\" content=\"Achetez P\u00e9trin \u00e0 spirale \/ p\u00e9trin \u00e0 p\u00e2te - 8 L - 4,5 kg de p\u00e2te - rose au meilleur prix, fiable et performant avec une livraison rapide\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gastora.eu\/en\/product\/ptrin-spirale-ptrin-pte-8-l-45-kg-de-pte-rose\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"P\u00e9trin \u00e0 spirale \/ p\u00e9trin \u00e0 p\u00e2te - 8 L - 4,5 kg de p\u00e2te - rose - Gastora\" \/>\n<meta property=\"og:description\" content=\"Achetez P\u00e9trin \u00e0 spirale \/ p\u00e9trin \u00e0 p\u00e2te - 8 L - 4,5 kg de p\u00e2te - rose au meilleur prix, fiable et performant avec une livraison rapide\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gastora.eu\/en\/product\/ptrin-spirale-ptrin-pte-8-l-45-kg-de-pte-rose\/\" \/>\n<meta property=\"og:site_name\" content=\"Gastora\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-28T16:57:28+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gastora.eu\\\/product\\\/ptrin-spirale-ptrin-pte-8-l-45-kg-de-pte-rose\\\/\",\"url\":\"https:\\\/\\\/gastora.eu\\\/product\\\/ptrin-spirale-ptrin-pte-8-l-45-kg-de-pte-rose\\\/\",\"name\":\"P\u00e9trin \u00e0 spirale \\\/ p\u00e9trin \u00e0 p\u00e2te - 8 L - 4,5 kg de p\u00e2te - rose - Gastora\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gastora.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gastora.eu\\\/product\\\/ptrin-spirale-ptrin-pte-8-l-45-kg-de-pte-rose\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gastora.eu\\\/product\\\/ptrin-spirale-ptrin-pte-8-l-45-kg-de-pte-rose\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gastora.eu\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/sp-1001-09361012.jpg\",\"datePublished\":\"2026-04-26T08:47:41+00:00\",\"dateModified\":\"2026-04-28T16:57:28+00:00\",\"description\":\"Achetez P\u00e9trin \u00e0 spirale \\\/ p\u00e9trin \u00e0 p\u00e2te - 8 L - 4,5 kg de p\u00e2te - rose au meilleur prix, fiable et performant avec une livraison rapide\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gastora.eu\\\/product\\\/ptrin-spirale-ptrin-pte-8-l-45-kg-de-pte-rose\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gastora.eu\\\/product\\\/ptrin-spirale-ptrin-pte-8-l-45-kg-de-pte-rose\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/gastora.eu\\\/product\\\/ptrin-spirale-ptrin-pte-8-l-45-kg-de-pte-rose\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gastora.eu\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/sp-1001-09361012.jpg\",\"contentUrl\":\"https:\\\/\\\/gastora.eu\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/sp-1001-09361012.jpg\",\"width\":1200,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gastora.eu\\\/product\\\/ptrin-spirale-ptrin-pte-8-l-45-kg-de-pte-rose\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/gastora.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/gastora.eu\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"P\u00e9trin \u00e0 spirale \\\/ p\u00e9trin \u00e0 p\u00e2te &#8211; 8 L &#8211; 4,5 kg de p\u00e2te &#8211; rose\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gastora.eu\\\/#website\",\"url\":\"https:\\\/\\\/gastora.eu\\\/\",\"name\":\"Gastora\",\"description\":\"\u00c9quipements professionnels CHR\",\"publisher\":{\"@id\":\"https:\\\/\\\/gastora.eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gastora.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gastora.eu\\\/#organization\",\"name\":\"Gastora\",\"url\":\"https:\\\/\\\/gastora.eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/gastora.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gastora.eu\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/ChatGPT-Image-2-janv.-2026-22_52_47-1.png\",\"contentUrl\":\"https:\\\/\\\/gastora.eu\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/ChatGPT-Image-2-janv.-2026-22_52_47-1.png\",\"width\":1536,\"height\":320,\"caption\":\"Gastora\"},\"image\":{\"@id\":\"https:\\\/\\\/gastora.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"P\u00e9trin \u00e0 spirale \/ p\u00e9trin \u00e0 p\u00e2te - 8 L - 4,5 kg de p\u00e2te - rose - Gastora","description":"Achetez P\u00e9trin \u00e0 spirale \/ p\u00e9trin \u00e0 p\u00e2te - 8 L - 4,5 kg de p\u00e2te - rose au meilleur prix, fiable et performant avec une livraison rapide","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gastora.eu\/en\/product\/ptrin-spirale-ptrin-pte-8-l-45-kg-de-pte-rose\/","og_locale":"en_US","og_type":"article","og_title":"P\u00e9trin \u00e0 spirale \/ p\u00e9trin \u00e0 p\u00e2te - 8 L - 4,5 kg de p\u00e2te - rose - Gastora","og_description":"Achetez P\u00e9trin \u00e0 spirale \/ p\u00e9trin \u00e0 p\u00e2te - 8 L - 4,5 kg de p\u00e2te - rose au meilleur prix, fiable et performant avec une livraison rapide","og_url":"https:\/\/gastora.eu\/en\/product\/ptrin-spirale-ptrin-pte-8-l-45-kg-de-pte-rose\/","og_site_name":"Gastora","article_modified_time":"2026-04-28T16:57:28+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/gastora.eu\/product\/ptrin-spirale-ptrin-pte-8-l-45-kg-de-pte-rose\/","url":"https:\/\/gastora.eu\/product\/ptrin-spirale-ptrin-pte-8-l-45-kg-de-pte-rose\/","name":"P\u00e9trin \u00e0 spirale \/ p\u00e9trin \u00e0 p\u00e2te - 8 L - 4,5 kg de p\u00e2te - rose - Gastora","isPartOf":{"@id":"https:\/\/gastora.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gastora.eu\/product\/ptrin-spirale-ptrin-pte-8-l-45-kg-de-pte-rose\/#primaryimage"},"image":{"@id":"https:\/\/gastora.eu\/product\/ptrin-spirale-ptrin-pte-8-l-45-kg-de-pte-rose\/#primaryimage"},"thumbnailUrl":"https:\/\/gastora.eu\/wp-content\/uploads\/2026\/04\/sp-1001-09361012.jpg","datePublished":"2026-04-26T08:47:41+00:00","dateModified":"2026-04-28T16:57:28+00:00","description":"Achetez P\u00e9trin \u00e0 spirale \/ p\u00e9trin \u00e0 p\u00e2te - 8 L - 4,5 kg de p\u00e2te - rose au meilleur prix, fiable et performant avec une livraison rapide","breadcrumb":{"@id":"https:\/\/gastora.eu\/product\/ptrin-spirale-ptrin-pte-8-l-45-kg-de-pte-rose\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gastora.eu\/product\/ptrin-spirale-ptrin-pte-8-l-45-kg-de-pte-rose\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/gastora.eu\/product\/ptrin-spirale-ptrin-pte-8-l-45-kg-de-pte-rose\/#primaryimage","url":"https:\/\/gastora.eu\/wp-content\/uploads\/2026\/04\/sp-1001-09361012.jpg","contentUrl":"https:\/\/gastora.eu\/wp-content\/uploads\/2026\/04\/sp-1001-09361012.jpg","width":1200,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/gastora.eu\/product\/ptrin-spirale-ptrin-pte-8-l-45-kg-de-pte-rose\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/gastora.eu\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/gastora.eu\/shop\/"},{"@type":"ListItem","position":3,"name":"P\u00e9trin \u00e0 spirale \/ p\u00e9trin \u00e0 p\u00e2te &#8211; 8 L &#8211; 4,5 kg de p\u00e2te &#8211; rose"}]},{"@type":"WebSite","@id":"https:\/\/gastora.eu\/#website","url":"https:\/\/gastora.eu\/","name":"Gastora","description":"\u00c9quipements professionnels CHR","publisher":{"@id":"https:\/\/gastora.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gastora.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/gastora.eu\/#organization","name":"Gastora","url":"https:\/\/gastora.eu\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/gastora.eu\/#\/schema\/logo\/image\/","url":"https:\/\/gastora.eu\/wp-content\/uploads\/2025\/12\/ChatGPT-Image-2-janv.-2026-22_52_47-1.png","contentUrl":"https:\/\/gastora.eu\/wp-content\/uploads\/2025\/12\/ChatGPT-Image-2-janv.-2026-22_52_47-1.png","width":1536,"height":320,"caption":"Gastora"},"image":{"@id":"https:\/\/gastora.eu\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/gastora.eu\/en\/wp-json\/wp\/v2\/product\/14934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gastora.eu\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gastora.eu\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gastora.eu\/en\/wp-json\/wp\/v2\/media\/8601"}],"wp:attachment":[{"href":"https:\/\/gastora.eu\/en\/wp-json\/wp\/v2\/media?parent=14934"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gastora.eu\/en\/wp-json\/wp\/v2\/product_brand?post=14934"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gastora.eu\/en\/wp-json\/wp\/v2\/product_cat?post=14934"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gastora.eu\/en\/wp-json\/wp\/v2\/product_tag?post=14934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}